{"id":1308,"date":"2017-04-27T11:10:54","date_gmt":"2017-04-27T09:10:54","guid":{"rendered":"http:\/\/blog.opal-net.fr\/?p=1308"},"modified":"2017-04-27T11:10:54","modified_gmt":"2017-04-27T09:10:54","slug":"opal-network-au-service-de-lefficacite-de-vos-missions","status":"publish","type":"post","link":"https:\/\/gestoo.fr\/actualites\/opal-network-au-service-de-lefficacite-de-vos-missions\/","title":{"rendered":"Opal Network au service de l\u2019efficacit\u00e9 de vos missions"},"content":{"rendered":"<div class=\"row\">\n<div class=\"span6\">\n<p align=\"justify\"><a href=\"http:\/\/opal-net.fr\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-1263 alignright\" src=\"http:\/\/blog.opal-net.fr\/wp-content\/uploads\/2017\/04\/petit-logo-transparent.png\" alt=\"\" width=\"170\" height=\"34\" srcset=\"https:\/\/gestoo.fr\/actualites\/wp-content\/uploads\/2017\/04\/petit-logo-transparent.png 170w, https:\/\/gestoo.fr\/actualites\/wp-content\/uploads\/2017\/04\/petit-logo-transparent-110x22.png 110w\" sizes=\"(max-width: 170px) 100vw, 170px\" \/>OPAL NETWORK<\/a> est le r\u00e9seau des consultants en optimisation et croissance des PME. Il s\u2019adresse \u00e0 des ind\u00e9pendants exp\u00e9riment\u00e9s, passionn\u00e9s d\u2019entreprises et d\u00e9sireux de mettre leurs comp\u00e9tences au service de leur environnement \u00e9conomique.<\/p>\n<\/div>\n<div class=\"span6\">\n<p align=\"justify\">Nous leur apportons le compl\u00e9ment n\u00e9cessaire \u00e0 la validation de leur d\u00e9marche et l\u2019accompagnement indispensable \u00e0 leur r\u00e9ussite. Consultants OPAL ils deviennent des professionnels du conseil et de la formation des dirigeants \u00e0 la gestion op\u00e9rationnelle et dynamique.<\/p>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>OPAL NETWORK est le r\u00e9seau des consultants en optimisation et croissance des PME. Il s\u2019adresse \u00e0 des ind\u00e9pendants exp\u00e9riment\u00e9s, passionn\u00e9s d\u2019entreprises et d\u00e9sireux de mettre leurs comp\u00e9tences au service de leur environnement \u00e9conomique.<\/p>\n","protected":false},"author":1,"featured_media":1300,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[3,7,8],"_links":{"self":[{"href":"https:\/\/gestoo.fr\/actualites\/wp-json\/wp\/v2\/posts\/1308"}],"collection":[{"href":"https:\/\/gestoo.fr\/actualites\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/gestoo.fr\/actualites\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/gestoo.fr\/actualites\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/gestoo.fr\/actualites\/wp-json\/wp\/v2\/comments?post=1308"}],"version-history":[{"count":1,"href":"https:\/\/gestoo.fr\/actualites\/wp-json\/wp\/v2\/posts\/1308\/revisions"}],"predecessor-version":[{"id":1309,"href":"https:\/\/gestoo.fr\/actualites\/wp-json\/wp\/v2\/posts\/1308\/revisions\/1309"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gestoo.fr\/actualites\/wp-json\/wp\/v2\/media\/1300"}],"wp:attachment":[{"href":"https:\/\/gestoo.fr\/actualites\/wp-json\/wp\/v2\/media?parent=1308"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/gestoo.fr\/actualites\/wp-json\/wp\/v2\/categories?post=1308"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/gestoo.fr\/actualites\/wp-json\/wp\/v2\/tags?post=1308"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}