{"id":1771,"date":"2019-02-06T16:32:27","date_gmt":"2019-02-06T15:32:27","guid":{"rendered":"http:\/\/opal-net.fr\/actualites\/?p=1771"},"modified":"2019-02-06T16:39:58","modified_gmt":"2019-02-06T15:39:58","slug":"laurent-averseng-rejoint-le-reseau-opal-dans-le-bas-rhin","status":"publish","type":"post","link":"https:\/\/gestoo.fr\/actualites\/laurent-averseng-rejoint-le-reseau-opal-dans-le-bas-rhin\/","title":{"rendered":"Laurent Averseng rejoint le r\u00e9seau Opal dans le Bas-Rhin"},"content":{"rendered":"<p>Laur\u00e9at de l&rsquo;ESSEC Business School, Laurent a commenc\u00e9 sa carri\u00e8re comme contr\u00f4leur de gestion puis directeur du contr\u00f4le de Gestion dans le Groupe <strong>Auchan<\/strong>. Il prend ensuite la direction d\u2019un r\u00e9seau d\u2019une cinquantaine de magasins <strong>ATAC<\/strong> pour un CA de plus de 500 Millions d\u2019Euros.<\/p>\n<p>En 2007 il reprend la soci\u00e9t\u00e9 <strong>PROMOUVOIR<\/strong> dans l\u2019\u00e9v\u00e8nementiel qu\u2019il va diriger pendant 10 ans.<\/p>\n<p><strong>Laurent<\/strong> rejoint aujourd\u2019hui Opal dans le Bas-Rhin pour accompagner les entreprises de son secteur dans leur d\u00e9veloppement.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Laur\u00e9at de l&rsquo;ESSEC Business School, Laurent a commenc\u00e9 sa carri\u00e8re comme contr\u00f4leur de gestion puis directeur du contr\u00f4le de Gestion&#8230;<\/p>\n","protected":false},"author":2,"featured_media":1772,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[17,5,12,10,23,21],"_links":{"self":[{"href":"https:\/\/gestoo.fr\/actualites\/wp-json\/wp\/v2\/posts\/1771"}],"collection":[{"href":"https:\/\/gestoo.fr\/actualites\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/gestoo.fr\/actualites\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/gestoo.fr\/actualites\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/gestoo.fr\/actualites\/wp-json\/wp\/v2\/comments?post=1771"}],"version-history":[{"count":2,"href":"https:\/\/gestoo.fr\/actualites\/wp-json\/wp\/v2\/posts\/1771\/revisions"}],"predecessor-version":[{"id":1774,"href":"https:\/\/gestoo.fr\/actualites\/wp-json\/wp\/v2\/posts\/1771\/revisions\/1774"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gestoo.fr\/actualites\/wp-json\/wp\/v2\/media\/1772"}],"wp:attachment":[{"href":"https:\/\/gestoo.fr\/actualites\/wp-json\/wp\/v2\/media?parent=1771"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/gestoo.fr\/actualites\/wp-json\/wp\/v2\/categories?post=1771"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/gestoo.fr\/actualites\/wp-json\/wp\/v2\/tags?post=1771"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}